{"id":5155,"date":"2026-04-20T14:05:04","date_gmt":"2026-04-20T12:05:04","guid":{"rendered":"https:\/\/ibz-bielefeld.de\/?p=5155"},"modified":"2026-04-20T14:06:18","modified_gmt":"2026-04-20T12:06:18","slug":"gemeinsam-laut-jugendliche-omas-gegen-alltagsrassismus","status":"publish","type":"post","link":"https:\/\/ibz-bielefeld.de\/es\/uncategorized\/gemeinsam-laut-jugendliche-omas-gegen-alltagsrassismus\/","title":{"rendered":"Juntos en voz alta: adolescentes &amp; abuelas contra el racismo cotidiano"},"content":{"rendered":"<p>El viernes, el <strong>17.04.<\/strong>, en el marco de la <strong>Semanas antirracistas de Bielefeld<\/strong> el <strong>IBZ \u2013 Educaci\u00f3n pol\u00edtica<\/strong>, El grupo House <strong>Futuro joven<\/strong>, el <strong>Abuelas contra la derecha<\/strong> y activista Nkrumah Mbouguen, ali\u00e1s<strong>afrocracia\u00bb<\/strong> para una noche abierta bajo el lema <strong>\u00abJuntos en voz alta: j\u00f3venes &amp; abuelas contra el racismo cotidiano\u00bb<\/strong> invitados.<\/p>\n\n\n\n<p>En un ambiente c\u00e1lido y abierto, hablamos sobre c\u00f3mo funciona el racismo cotidiano, c\u00f3mo podemos fortalecernos mutuamente y qu\u00e9 pasos comunes son necesarios para promover la diversidad y el respeto. Ellos han enfatizado particularmente <strong>Abuelas contra la derecha<\/strong>, la importancia de los encuentros intergeneracionales: Las experiencias que han tenido en su propia vida no deben ser olvidadas. Al mismo tiempo, estaban ansiosos por entender lo que los j\u00f3venes est\u00e1n experimentando hoy en d\u00eda, especialmente en una sociedad muy diversa.<\/p>\n\n\n\n<p>Los j\u00f3venes han informado abiertamente sobre sus propias experiencias con el racismo. Aclararon lo importante que es luchar activamente contra el racismo, informarse y formar parte de la labor de sensibilizaci\u00f3n y educaci\u00f3n de \u2011. El evento ofreci\u00f3 muchos impulsos, nuevas perspectivas y mucho espacio para el intercambio personal. La presentaci\u00f3n estuvo a cargo de Ogulcan Yumusat y Anja Obendorfer. <\/p>\n\n\n\n<p>\u00a1Un sincero agradecimiento a todos los que estuvieron all\u00ed y se enriquecieron esta noche con sus contribuciones!<br><\/p>","protected":false},"excerpt":{"rendered":"<p>Am Freitag, den 17.04., haben im Rahmen der Bielefelder Antirassismuswochen das IBZ \u2013 Politische Bildung, die Hausgruppe Young Future, die Omas gegen Rechts sowie der Aktivist Nkrumah Mbouguen, ali\u00e1s &#8222;Afrokratie&#8220;&#8230;<\/p>","protected":false},"author":2,"featured_media":5156,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"_links":{"self":[{"href":"https:\/\/ibz-bielefeld.de\/es\/wp-json\/wp\/v2\/posts\/5155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibz-bielefeld.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibz-bielefeld.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibz-bielefeld.de\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ibz-bielefeld.de\/es\/wp-json\/wp\/v2\/comments?post=5155"}],"version-history":[{"count":3,"href":"https:\/\/ibz-bielefeld.de\/es\/wp-json\/wp\/v2\/posts\/5155\/revisions"}],"predecessor-version":[{"id":5159,"href":"https:\/\/ibz-bielefeld.de\/es\/wp-json\/wp\/v2\/posts\/5155\/revisions\/5159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibz-bielefeld.de\/es\/wp-json\/wp\/v2\/media\/5156"}],"wp:attachment":[{"href":"https:\/\/ibz-bielefeld.de\/es\/wp-json\/wp\/v2\/media?parent=5155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibz-bielefeld.de\/es\/wp-json\/wp\/v2\/categories?post=5155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibz-bielefeld.de\/es\/wp-json\/wp\/v2\/tags?post=5155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}